{"id":17393,"date":"2023-01-27T15:16:02","date_gmt":"2023-01-27T15:16:02","guid":{"rendered":"https:\/\/cortenhuys.nl\/2023\/01\/27\/brauereifuehrung-grolsch\/"},"modified":"2023-03-29T11:14:34","modified_gmt":"2023-03-29T11:14:34","slug":"brauereifuehrung-grolsch","status":"publish","type":"post","link":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/","title":{"rendered":"Brauereif\u00fchrung Grolsch"},"content":{"rendered":"\n<p>Erleben Sie Grolsch! Entdecken Sie alles \u00fcber unser Bier, die Werbespots, die Geschichte oder die weltber\u00fchmte Grolsch-B\u00fcgelflasche. Grolsch bietet mehrere Touren an:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Brauereif\u00fchrung Grolsch<\/li>\n\n\n\n<li>Bierkennertour<\/li>\n\n\n\n<li>Brauereif\u00fchrung mit verschiedenen Buffets<\/li>\n<\/ul>\n\n<p>Alle Touren dauern ca. 2,5 Stunden.<\/p>\n\n<p>Die Grolsch-Fabrik ist 11 Kilometer von CortenHuys entfernt.<\/p>\n\n<p>Weitere Informationen finden Sie unter: <a href=\"https:\/\/www.grolsch.nl\/brouwerij-tour.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.grolsch.nl\/brouwerij-tour.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erleben Sie Grolsch! Entdecken Sie alles \u00fcber unser Bier, die Werbespots, die Geschichte oder die weltber\u00fchmte Grolsch-B\u00fcgelflasche. Grolsch bietet mehrere Touren an: Alle Touren dauern ca. 2,5 Stunden. Die Grolsch-Fabrik ist 11 Kilometer von CortenHuys entfernt. Weitere Informationen finden Sie unter: https:\/\/www.grolsch.nl\/brouwerij-tour.html<\/p>\n","protected":false},"author":1,"featured_media":16869,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63,71],"tags":[],"class_list":["post-17393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktivitaten","category-kultur"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brauereif\u00fchrung Grolsch - CortenHuys<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brauereif\u00fchrung Grolsch - CortenHuys\" \/>\n<meta property=\"og:description\" content=\"Erleben Sie Grolsch! Entdecken Sie alles \u00fcber unser Bier, die Werbespots, die Geschichte oder die weltber\u00fchmte Grolsch-B\u00fcgelflasche. Grolsch bietet mehrere Touren an: Alle Touren dauern ca. 2,5 Stunden. Die Grolsch-Fabrik ist 11 Kilometer von CortenHuys entfernt. Weitere Informationen finden Sie unter: https:\/\/www.grolsch.nl\/brouwerij-tour.html\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/\" \/>\n<meta property=\"og:site_name\" content=\"CortenHuys\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T15:16:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-29T11:14:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/01\/Grolsch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1664\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cortenhuys\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cortenhuys\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/\"},\"author\":{\"name\":\"Cortenhuys\",\"@id\":\"https:\/\/cortenhuys.nl\/de\/#\/schema\/person\/8c9e5d913335edc044f2e11d503efba2\"},\"headline\":\"Brauereif\u00fchrung Grolsch\",\"datePublished\":\"2023-01-27T15:16:02+00:00\",\"dateModified\":\"2023-03-29T11:14:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/\"},\"wordCount\":59,\"publisher\":{\"@id\":\"https:\/\/cortenhuys.nl\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/01\/Grolsch.jpg\",\"articleSection\":[\"Aktivit\u00e4ten\",\"Kultur\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/\",\"url\":\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/\",\"name\":\"Brauereif\u00fchrung Grolsch - CortenHuys\",\"isPartOf\":{\"@id\":\"https:\/\/cortenhuys.nl\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/01\/Grolsch.jpg\",\"datePublished\":\"2023-01-27T15:16:02+00:00\",\"dateModified\":\"2023-03-29T11:14:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#primaryimage\",\"url\":\"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/01\/Grolsch.jpg\",\"contentUrl\":\"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/01\/Grolsch.jpg\",\"width\":2500,\"height\":1664},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cortenhuys.nl\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brauereif\u00fchrung Grolsch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cortenhuys.nl\/de\/#website\",\"url\":\"https:\/\/cortenhuys.nl\/de\/\",\"name\":\"CortenHuys\",\"description\":\"Luxe wellness lodge in Twente\",\"publisher\":{\"@id\":\"https:\/\/cortenhuys.nl\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cortenhuys.nl\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cortenhuys.nl\/de\/#organization\",\"name\":\"CortenHuys\",\"url\":\"https:\/\/cortenhuys.nl\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/cortenhuys.nl\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/02\/cortenhuys-Large.png\",\"contentUrl\":\"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/02\/cortenhuys-Large.png\",\"width\":1280,\"height\":252,\"caption\":\"CortenHuys\"},\"image\":{\"@id\":\"https:\/\/cortenhuys.nl\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cortenhuys.nl\/de\/#\/schema\/person\/8c9e5d913335edc044f2e11d503efba2\",\"name\":\"Cortenhuys\",\"sameAs\":[\"http:\/\/cortenhuys.nl\"],\"url\":\"https:\/\/cortenhuys.nl\/de\/author\/cortenhuys\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brauereif\u00fchrung Grolsch - CortenHuys","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/","og_locale":"de_DE","og_type":"article","og_title":"Brauereif\u00fchrung Grolsch - CortenHuys","og_description":"Erleben Sie Grolsch! Entdecken Sie alles \u00fcber unser Bier, die Werbespots, die Geschichte oder die weltber\u00fchmte Grolsch-B\u00fcgelflasche. Grolsch bietet mehrere Touren an: Alle Touren dauern ca. 2,5 Stunden. Die Grolsch-Fabrik ist 11 Kilometer von CortenHuys entfernt. Weitere Informationen finden Sie unter: https:\/\/www.grolsch.nl\/brouwerij-tour.html","og_url":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/","og_site_name":"CortenHuys","article_published_time":"2023-01-27T15:16:02+00:00","article_modified_time":"2023-03-29T11:14:34+00:00","og_image":[{"width":2500,"height":1664,"url":"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/01\/Grolsch.jpg","type":"image\/jpeg"}],"author":"Cortenhuys","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Cortenhuys"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#article","isPartOf":{"@id":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/"},"author":{"name":"Cortenhuys","@id":"https:\/\/cortenhuys.nl\/de\/#\/schema\/person\/8c9e5d913335edc044f2e11d503efba2"},"headline":"Brauereif\u00fchrung Grolsch","datePublished":"2023-01-27T15:16:02+00:00","dateModified":"2023-03-29T11:14:34+00:00","mainEntityOfPage":{"@id":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/"},"wordCount":59,"publisher":{"@id":"https:\/\/cortenhuys.nl\/de\/#organization"},"image":{"@id":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#primaryimage"},"thumbnailUrl":"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/01\/Grolsch.jpg","articleSection":["Aktivit\u00e4ten","Kultur"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/","url":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/","name":"Brauereif\u00fchrung Grolsch - CortenHuys","isPartOf":{"@id":"https:\/\/cortenhuys.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#primaryimage"},"image":{"@id":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#primaryimage"},"thumbnailUrl":"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/01\/Grolsch.jpg","datePublished":"2023-01-27T15:16:02+00:00","dateModified":"2023-03-29T11:14:34+00:00","breadcrumb":{"@id":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#primaryimage","url":"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/01\/Grolsch.jpg","contentUrl":"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/01\/Grolsch.jpg","width":2500,"height":1664},{"@type":"BreadcrumbList","@id":"https:\/\/cortenhuys.nl\/de\/2023\/01\/27\/brauereifuehrung-grolsch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cortenhuys.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Brauereif\u00fchrung Grolsch"}]},{"@type":"WebSite","@id":"https:\/\/cortenhuys.nl\/de\/#website","url":"https:\/\/cortenhuys.nl\/de\/","name":"CortenHuys","description":"Luxe wellness lodge in Twente","publisher":{"@id":"https:\/\/cortenhuys.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cortenhuys.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cortenhuys.nl\/de\/#organization","name":"CortenHuys","url":"https:\/\/cortenhuys.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cortenhuys.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/02\/cortenhuys-Large.png","contentUrl":"https:\/\/cortenhuys.nl\/wp-content\/uploads\/2023\/02\/cortenhuys-Large.png","width":1280,"height":252,"caption":"CortenHuys"},"image":{"@id":"https:\/\/cortenhuys.nl\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cortenhuys.nl\/de\/#\/schema\/person\/8c9e5d913335edc044f2e11d503efba2","name":"Cortenhuys","sameAs":["http:\/\/cortenhuys.nl"],"url":"https:\/\/cortenhuys.nl\/de\/author\/cortenhuys\/"}]}},"_links":{"self":[{"href":"https:\/\/cortenhuys.nl\/de\/wp-json\/wp\/v2\/posts\/17393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cortenhuys.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cortenhuys.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cortenhuys.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cortenhuys.nl\/de\/wp-json\/wp\/v2\/comments?post=17393"}],"version-history":[{"count":3,"href":"https:\/\/cortenhuys.nl\/de\/wp-json\/wp\/v2\/posts\/17393\/revisions"}],"predecessor-version":[{"id":17396,"href":"https:\/\/cortenhuys.nl\/de\/wp-json\/wp\/v2\/posts\/17393\/revisions\/17396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cortenhuys.nl\/de\/wp-json\/wp\/v2\/media\/16869"}],"wp:attachment":[{"href":"https:\/\/cortenhuys.nl\/de\/wp-json\/wp\/v2\/media?parent=17393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cortenhuys.nl\/de\/wp-json\/wp\/v2\/categories?post=17393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cortenhuys.nl\/de\/wp-json\/wp\/v2\/tags?post=17393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}